{"id":1777,"date":"2012-02-12T10:44:28","date_gmt":"2012-02-12T09:44:28","guid":{"rendered":"http:\/\/lisewulff.com\/wordpress\/?p=1777"},"modified":"2016-02-12T11:32:29","modified_gmt":"2016-02-12T10:32:29","slug":"inside-outside","status":"publish","type":"post","link":"https:\/\/lisewulff.com\/wordpress\/archives\/1777","title":{"rendered":"Inside Outside"},"content":{"rendered":"<p>Ongoing project with man size sculptures, all with different external looks and a secret inside.<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi.jpg\" rel=\"attachment wp-att-1784\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1784\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi-682x1024.jpg\" alt=\"_MG_1907-kopi\" width=\"682\" height=\"1024\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi-682x1024.jpg 682w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi-200x300.jpg 200w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi-768x1152.jpg 768w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi-800x1200.jpg 800w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi-500x750.jpg 500w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/MG_1907-kopi.jpg 1181w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/Gaffa-1.jpg\" rel=\"attachment wp-att-1788\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1788\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/Gaffa-1.jpg\" alt=\"Gaffa (1)\" width=\"609\" height=\"345\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/Gaffa-1.jpg 609w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/Gaffa-1-300x170.jpg 300w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2012\/02\/Gaffa-1-500x283.jpg 500w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2013\/09\/Wulff-21.jpeg\" rel=\"attachment wp-att-647\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-647\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2013\/09\/Wulff-21.jpeg\" alt=\"Wulff 2\" width=\"854\" height=\"572\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2013\/09\/Wulff-21.jpeg 854w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2013\/09\/Wulff-21-300x200.jpeg 300w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2013\/09\/Wulff-21-800x535.jpeg 800w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2013\/09\/Wulff-21-500x334.jpeg 500w\" sizes=\"auto, (max-width: 854px) 100vw, 854px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ongoing project with man size sculptures, all with different external looks and a secret inside. &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":648,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-works"],"_links":{"self":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":9,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts\/1777\/revisions"}],"predecessor-version":[{"id":1790,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts\/1777\/revisions\/1790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/media\/648"}],"wp:attachment":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/categories?post=1777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/tags?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}