{"id":1791,"date":"2009-02-12T11:36:40","date_gmt":"2009-02-12T10:36:40","guid":{"rendered":"http:\/\/lisewulff.com\/wordpress\/?p=1791"},"modified":"2016-02-12T11:37:33","modified_gmt":"2016-02-12T10:37:33","slug":"for-an-indefinite-time","status":"publish","type":"post","link":"https:\/\/lisewulff.com\/wordpress\/archives\/1791","title":{"rendered":"For an Indefinite Time"},"content":{"rendered":"<p>A series of 1 meter tall sculptures<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0549-kopi.jpg\" rel=\"attachment wp-att-559\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-559\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0549-kopi-693x1024.jpg\" alt=\"IMG_0549-kopi\" width=\"693\" height=\"1024\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0549-kopi-693x1024.jpg 693w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0549-kopi-203x300.jpg 203w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0549-kopi.jpg 1701w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0623.jpg\" rel=\"attachment wp-att-558\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-558\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0623-611x1024.jpg\" alt=\"IMG_0623\" width=\"611\" height=\"1024\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0623-611x1024.jpg 611w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0623-179x300.jpg 179w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0573.jpg\" rel=\"attachment wp-att-557\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-557\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0573-644x1024.jpg\" alt=\"IMG_0573\" width=\"644\" height=\"1024\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0573-644x1024.jpg 644w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0573-188x300.jpg 188w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0567.jpg\" rel=\"attachment wp-att-556\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-556\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0567-571x1024.jpg\" alt=\"IMG_0567\" width=\"571\" height=\"1024\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0567-571x1024.jpg 571w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0567-167x300.jpg 167w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0567-800x1433.jpg 800w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0567.jpg 1946w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0603-kopi.jpg\" rel=\"attachment wp-att-555\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-555\" src=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0603-kopi-676x1024.jpg\" alt=\"IMG_0603-kopi\" width=\"676\" height=\"1024\" srcset=\"https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0603-kopi-676x1024.jpg 676w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0603-kopi-198x300.jpg 198w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0603-kopi-800x1211.jpg 800w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0603-kopi-500x757.jpg 500w, https:\/\/lisewulff.com\/wordpress\/wp-content\/uploads\/2014\/10\/IMG_0603-kopi.jpg 1984w\" sizes=\"auto, (max-width: 676px) 100vw, 676px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A series of 1 meter tall sculptures &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":560,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-1791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-works"],"_links":{"self":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts\/1791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/comments?post=1791"}],"version-history":[{"count":1,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts\/1791\/revisions"}],"predecessor-version":[{"id":1792,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/posts\/1791\/revisions\/1792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/media\/560"}],"wp:attachment":[{"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/media?parent=1791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/categories?post=1791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lisewulff.com\/wordpress\/wp-json\/wp\/v2\/tags?post=1791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}